{"id":943,"date":"2021-10-04T13:23:38","date_gmt":"2021-10-04T17:23:38","guid":{"rendered":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/?p=943"},"modified":"2021-11-10T15:48:16","modified_gmt":"2021-11-10T20:48:16","slug":"entamons-avec-confiance-cette-nouvelle-annee-scolaire","status":"publish","type":"post","link":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/entamons-avec-confiance-cette-nouvelle-annee-scolaire\/","title":{"rendered":"Entamons avec confiance cette nouvelle ann\u00e9e scolaire"},"content":{"rendered":"<p>Malgr\u00e9 une autre rentr\u00e9e sous le signe de la pand\u00e9mie, nous sommes pr\u00eats, forts de notre exp\u00e9rience et surtout des innovations et habilet\u00e9s que nous avons d\u00e9velopp\u00e9es pour pallier aux diff\u00e9rents d\u00e9fis que ce contexte apporte. Nous pouvons entamer avec confiance cette nouvelle ann\u00e9e.<\/p>\n<p>Comme vous en avez d\u00e9j\u00e0 \u00e9t\u00e9 inform\u00e9s, nous d\u00e9butons l&rsquo;ann\u00e9e avec des changements temporaires \u00e0 la direction du CREP.\u00a0<a href=\"mailto:boucherv@csdm.qc.ca\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"1\">Mme Val\u00e9rie Boucher<\/a>\u00a0poursuivra l\u2019int\u00e9rim \u00e0 la direction en l\u2019absence de M. Alain Guillemette. Par ailleurs, nous sommes heureux d\u2019accueillir\u00a0<a href=\"mailto:herouxmc@csdm.qc.ca\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"2\">Mme Marie-Claude H\u00e9roux<\/a>, comme directrice adjointe int\u00e9rimaire en remplacement du poste d&rsquo;adjoint\u00a0de Mme\u00a0Val\u00e9rie Boucher. C\u2019est avec beaucoup d\u2019enthousiasme que Mme H\u00e9roux se joint \u00e0 notre \u00e9quipe et nous savons qu\u2019elle sera\u00a0une\u00a0collaboratrice sur laquelle vous pourrez compter. N\u2019h\u00e9sitez donc pas \u00e0 communiquer avec elle si vous avez des questions ou des demandes. De plus, nous d\u00e9sirons vous rappeler l\u2019absence pour une dur\u00e9e ind\u00e9termin\u00e9e de M. Jean-Jacques Ghabro, directeur adjoint. Les enseignants avec lesquels il travaillait en collaboration seront donc appel\u00e9s \u00e0 travailler avec\u00a0<a href=\"mailto:gagnonclau@csdm.qc.ca\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"3\">Mme Claude Gagnon<\/a>\u00a0ou\u00a0<a href=\"mailto:herouxmc@csdm.qc.ca\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"4\">Mme Marie-Claude H\u00e9roux<\/a>.<\/p>\n<p><strong>Informez-vous quelle sera la direction adjointe qui travaillera en collaboration avec vous cette ann\u00e9e<\/strong><\/p>\n<p>Nous avons redistribu\u00e9 les mandats \u00e0 la direction du CREP. Il se peut que vous ayez \u00e0 vous r\u00e9f\u00e9rer \u00e0 une nouvelle personne par rapport \u00e0 ce qui vous a d\u00e9j\u00e0 \u00e9t\u00e9 communiqu\u00e9 pr\u00e9c\u00e9demment. Veuillez donc prendre connaissance du tableau ci-dessous:<\/p>\n<ul>\n<li><a href=\"https:\/\/iclecrep.us14.list-manage.com\/track\/click?u=73b2a01dab12a6b4003a69e3d&amp;id=cbab7e7a5a&amp;e=51104d0114\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"5\"><strong>Cliquez ici pour t\u00e9l\u00e9charger le\u00a0<em>Tableau Organismes \u2013 adjoints &#8211; enseignants\u00a0du CREP 2021\u00a0<\/em><\/strong><\/a><\/li>\n<\/ul>\n<p>En toute collaboration,<\/p>\n<p>L&rsquo;\u00e9quipe de direction<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malgr\u00e9 une autre rentr\u00e9e sous le signe de la pand\u00e9mie, nous sommes pr\u00eats, forts de notre exp\u00e9rience et surtout des&hellip;<\/p>\n","protected":false},"author":1,"featured_media":944,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,13],"tags":[],"class_list":["post-943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-la-une","category-general"],"_links":{"self":[{"href":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/wp-json\/wp\/v2\/posts\/943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/wp-json\/wp\/v2\/comments?post=943"}],"version-history":[{"count":1,"href":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/wp-json\/wp\/v2\/posts\/943\/revisions"}],"predecessor-version":[{"id":945,"href":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/wp-json\/wp\/v2\/posts\/943\/revisions\/945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/wp-json\/wp\/v2\/media\/944"}],"wp:attachment":[{"href":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/wp-json\/wp\/v2\/media?parent=943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/wp-json\/wp\/v2\/categories?post=943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infocrep.cssdm.gouv.qc.ca\/enseignants\/wp-json\/wp\/v2\/tags?post=943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}